{"id":48161,"date":"2020-07-02T20:40:26","date_gmt":"2020-07-02T18:40:26","guid":{"rendered":"https:\/\/www.ericfavre.com\/lifestyle\/?page_id=48161"},"modified":"2021-04-22T20:45:23","modified_gmt":"2021-04-22T18:45:23","slug":"les-burpees","status":"publish","type":"page","link":"https:\/\/www.ericfavre.com\/lifestyle\/les-burpees\/","title":{"rendered":"Les Burpees"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"48161\" class=\"elementor elementor-48161\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-16555cd5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16555cd5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-472c63a5\" data-id=\"472c63a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7f6026 elementor-widget elementor-widget-image\" data-id=\"d7f6026\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ericfavre.com\">\n\t\t\t\t\t\t\t<img width=\"300\" height=\"96\" src=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/02\/logo-new-EF-300x96.png\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/02\/logo-new-EF-300x96.png 300w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/02\/logo-new-EF.png 389w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-4c076912 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4c076912\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49f3ab8e\" data-id=\"49f3ab8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fb14ec7 elementor-absolute elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3fb14ec7\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Les Burpees<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-2e7b66dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e7b66dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e57acb0\" data-id=\"2e57acb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418a9009 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"418a9009\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"437\" src=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-1024x437.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-1024x437.jpg 1024w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-300x128.jpg 300w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-768x328.jpg 768w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-1536x655.jpg 1536w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-1170x499.jpg 1170w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees-585x250.jpg 585w, https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/06\/burpees.jpg 1568w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36a279f8 elementor-widget elementor-widget-spacer\" data-id=\"36a279f8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f0ee504 elementor-widget elementor-widget-text-editor\" data-id=\"5f0ee504\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>Quand on commence \u00e0 faire du sport ou \u00e0 entreprendre des activit\u00e9s physiques, on n\u2019est pas toujours cal\u00e9 sur toutes les techniques et tous les mouvements susceptibles de nous aider \u00e0 atteindre nos objectifs. Face \u00e0 cela, il est parfois important de se renseigner, surtout si l\u2019on d\u00e9bute. Pour les d\u00e9butants, voici le guide des Burpees, un <b><a href=\"https:\/\/www.ericfavre.com\/lifestyle\/les-exercices-pliometriques\/\">exercice pliom\u00e9trique<\/a><\/b>, qui va aider \u00e0 am\u00e9liorer la condition physique.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c2a5be elementor-widget elementor-widget-spacer\" data-id=\"49c2a5be\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b83df27 elementor-widget elementor-widget-heading\" data-id=\"b83df27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les burpees, \u00e7a fait quoi\u00a0?  <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47db9b73 elementor-widget elementor-widget-spacer\" data-id=\"47db9b73\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2ba071 elementor-widget elementor-widget-text-editor\" data-id=\"3c2ba071\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>Avant de savoir ce que fait le burpee, il faut d\u2019abord d\u00e9finir ce que c\u2019est. Le <strong><em>burpee<\/em><\/strong>\u00a0est un exercice de musculation\u00a0 et d&#8217;a\u00e9robic\u00a0qui sollicite l&#8217;ensemble du corps. Son nom est issu de celui du physiologiste\u00a0am\u00e9ricain\u00a0 Royal H. Burpee, qui l&#8217;a d\u00e9velopp\u00e9 \u00e0 l&#8217;occasion de sa th\u00e8se de physiologie appliqu\u00e9e, soutenue en 1940 \u00e0 l&#8217;universit\u00e9 de Columbia.<\/p><p>\u00a0<\/p><p>D\u2019origine, l&#8217;exercice consiste en un encha\u00eenement \u00e0 r\u00e9p\u00e9ter en boucle\u00a0: une flexion des jambes les mains au sol, suivie d&#8217;un lancer des pieds en arri\u00e8re pour arriver en position de planche, tout en gardant les bras tendus. Il faut ensuite effectuer un retour en position de squat avant de finalement se relever.<\/p><p>\u00a0<\/p><p>Au fil des ann\u00e9es, de nombreuses variantes ont \u00e9t\u00e9 int\u00e9gr\u00e9es au sein de la boucle. Les plus communs consistent en un saut \u00e0 la derni\u00e8re \u00e9tape ou une pompe\u00a0au moment de la position de planche.<\/p><p>\u00a0<\/p><p>Le burpee est un exercice fonctionnel car il mobilise de fa\u00e7on coordonn\u00e9e de nombreux muscles lors de son ex\u00e9cution. Parmi les muscles les plus sollicit\u00e9s figurent\u00a0:<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Les triceps<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0l\u2019avant de l&#8217;\u00e9paule<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0le grand pectoral<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0les trap\u00e8zes et tous les fixateurs d&#8217;omoplates<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0la sangle abdominale<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0les fl\u00e9chisseurs de hanche<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0les cuisses, les fessiers, les ischios et les mollets.<\/p><p>\u00a0<\/p><p>L\u2019ex\u00e9cution dynamique des burpees demande un effort de gainage\/fixation important, ce qui rajoute de la difficult\u00e9 \u00e0 sa r\u00e9alisation.<\/p><p>\u00a0<\/p><p>Le travail \u00ab en cha\u00eene \u00bb des burpees s\u2019apparente aux actions quotidiennes de la vie courante: se baisser, se mettre au sol, se relever, sauter. Le burpee est tr\u00e8s utilis\u00e9 dans le monde militaire, mais aussi dans les courses d\u2019obstacles comme les Reebok Spartan Race.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af5f3f8 elementor-widget elementor-widget-spacer\" data-id=\"af5f3f8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87126ca elementor-widget elementor-widget-EricFavre_FormSIB1\" data-id=\"87126ca\" data-element_type=\"widget\" data-widget_type=\"EricFavre_FormSIB1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script src='https:\/\/www.google.com\/recaptcha\/api.js'><\/script>\r\n<style>\r\n\/*fonts *\/  \r\nbody, .wpst-row, #wpst-company-name, h1.title, .wpst-alert_success, .wpst-description, .wpst-button, .wpst-row .wpst-lbl-tinyltr, .wpst-row2, input[type=\"text\"], input[type=\"radio\"] {\r\n    font-family: \"Helvetica Neue\", Helvetica, Arial, sans-serif;\r\n}\r\n.wpst-row, #wpst-company-name, h1.title {\r\n    line-height: 150% !important;\r\n}\r\ninput:focus-visible {\r\noutline-offset: 0px;\r\n}\r\ndiv.wpst-needsfilled input {\r\n    border-color: #B94A48 !important;\r\n    color: #B94A48 !important;\r\n}\r\ndiv.wpst-needsfilled {\r\n    color: #B94A48 !important;\r\n}\r\n.wpst-alert-success button.wpst-close {\r\n    right: 10px;\r\n    color: inherit;\r\n    background: 0 0;\r\n    border: 0;\r\n    padding: 0px;\r\n    -webkit-appearance: none;\r\n    cursor: pointer;\r\n    font-weight: bold;\r\n    font-size: 16px;\r\n}\r\n.wpst-alert-success {\r\n    font-family: \"Helvetica Neue\", Helvetica, Arial, sans-serif;\r\n    border: 1px solid #13ce66;\r\n    border-radius: 5px !important;\r\n    padding: 1rem 1.7rem;\r\n    background-color : #DFF0D8;\r\n    border-color: #D6E9C6;\r\n    color: #468847;\r\n    text-align: justify;\r\n}\r\n.wpst-alert-success p {\r\n    margin-bottom: 5px;\r\n    float:right;\r\n}\r\n.wpst-alert {\r\n    border: 1px solid rgba(0, 0, 0, 0);\r\n    padding: 1rem 1.7rem;\r\n    border-radius: .2rem;\r\n    text-align: justify;\r\n    font-size: 15px;\r\n    text-shadow: 0 1px 0 rgba(255, 255, 255, 0.5);\r\n}\r\n.wpst-acmp_sib_form {\r\n    width: 750px;\r\n    height: 882px;\r\n    margin-left: auto;\r\n    margin-right: auto;\r\n    padding: 10px;\r\n    border: 1px solid #dedede;\r\n}\r\n.wpst-acmp_sib_form_right {\r\n    padding-left: 10px;\r\n}\r\n.wpst-elementor iframe, .wpst-elementor object, .wpst-elementor video {\r\n    max-width: 100%;\r\n    width: 100%;\r\n    margin: 0;\r\n    line-height: 1;\r\n    border: none;\r\n}\r\n\r\n\/* Error Message Styles *\/\r\n.wpst-alert-danger {\r\n    background: none;\r\n    color: #842029;\r\n    border: none;\r\n    border-radius: 4px;\r\n    position: absolute; \/* Keep absolute positioning *\/\r\n    margin-right: auto; \/* Center horizontally *\/\r\n    margin-left: auto; \/* Adjust the left positioning to truly center *\/\r\n    width: 100%; \/* Ensure full width *\/\r\n    padding: 0; \/* No padding to avoid shifting layout *\/\r\n    z-index: 999; \/* Keep on top of other content *\/\r\n}\r\n.wpst-alert-danger .wpst-close {\r\n    float: right;\r\n    background: none;\r\n    border: none;\r\n    color: #842029;\r\n    font-weight: bold;\r\n    cursor: pointer;\r\n}\r\n\/* error for reCaptcha*\/\r\n.wpst-alert-recaptcha {\r\n    background: none;\r\n    color: #842029;\r\n    border: none;\r\n    border-radius: 4px;\r\n    position: absolute;\r\n    margin-right: auto;\r\n    margin-left: auto;\r\n    width: 100%;\r\n    padding: 0;\r\n    z-index: 999;\r\n    margin-top: -18px; \/* Specific margin for reCAPTCHA *\/\r\n}\r\n.wpst-alert-recaptcha .wpst-close {\r\n    float: right;\r\n    background: none;\r\n    border: none;\r\n    color: #842029;\r\n    font-weight: bold;\r\n    cursor: pointer;\r\n}\r\n\/* Success Message Styles *\/\r\n.wpst-alert-success {\r\n    margin-top: -38px;\r\n    padding: 16px 27.2px;\r\n    background-color: #DFF0D8;\r\n    border-color: #D6E9C6;\r\n    color: #468847;\r\n    border: 1px solid #c3e6cb;\r\n    border-radius: 4px;\r\n}\r\n.wpst-alert-success .wpst-close {\r\n    float: right;\r\n    background: none;\r\n    border: none;\r\n    color: inherit;\r\n    font-weight: bold;\r\n    cursor: pointer;\r\n}\r\n\r\n#efForm {\r\n  transition: all 500ms !important;\r\n}\r\n  \r\n\/* Success Message Styles *\/\r\ninput[type=\"text\"] {\r\n    border: 1px solid #CCCCCC;\r\n    padding: 8px 4px;\r\n    width: 100%;\r\n    min-width: auto;\r\n    box-sizing: border-box;\r\n    -webkit-border-radius: 4px;\r\n    font-size: 13px;\r\n    -webkit-appearance: none;\r\n    padding: 4px;\r\n    width: 200px;\r\n}\r\ninput[type=\"radio\"] {\r\n    min-width: 20px;\r\n    width: 20px;\r\n    margin-right: 2%;\r\n    padding: 12px 5px;\r\n    border: none;\r\n    -moz-border-radius: none;\r\n    border-radius: none;\r\n    -webkit-border-radius: none;\r\n}\r\ninput[type=\"radio\"] {\r\n    -webkit-appearance: radio;\r\n    width: auto !important;\r\n    margin-left: 10px;\r\n}\r\n  .wpst-row{\r\n    padding: 10px 20px; \r\n  }\r\n.wpst-row2 {\r\n    padding: 5px 40px !important;\r\n}\r\n\r\n\r\n@media (max-width: 767px) {\r\n\r\n    \r\n.wpst-acmp_sib_form {\r\n    width: auto !important;\r\n    height: auto !important;\r\n  padding: 0px !important;\r\n  border: none !important;\r\n}\r\n.wpst-sib-container {\r\n    margin-left: auto !important;\r\n    width: auto !important;\r\n    margin-right: auto !important;\r\n    border-radius: 4px;\r\n    position: relative;\r\n    margin: 0px;\r\n    text-align: left;\r\n    background: rgb(0, 0, 0) !important;\r\n    padding: 25px 15px 15px !important;\r\n    border-width: 0px !important;\r\n    border-color: transparent !important;\r\n}\r\n.wpst-description {\r\n    padding: 10px 15px;\r\n    border-bottom: 1px solid rgb(204, 204, 204);\r\n    font-family: \"Helvetica Neue\", Helvetica, Arial, sans-serif;\r\n    color: rgb(255, 255, 255) !important;\r\n    font-size: 14px;\r\n    display: none;\r\n}\r\n.wpst-row {\r\n    padding: 10px;\r\n    font-size: 14px !important;\r\n    position: relative;\r\n    font-family: \"Helvetica Neue\", Helvetica, Arial, sans-serif;\r\n    color: rgb(255, 255, 255) !important;\r\n    left: 0px;\r\n    top: 0px;\r\n}\r\n.wpst-button {\r\n    font-family: \"Helvetica Neue\", Helvetica, Arial, sans-serif;\r\n    color: rgb(0, 0, 0) !important;\r\n    background: rgb(255, 255, 255) !important;\r\n    display: inline-block;\r\n    white-space: nowrap;\r\n    min-height: 30px;\r\n    margin: 0px 5px 0px 0px;\r\n    padding: 0px 10px;\r\n    text-decoration: none;\r\n    text-transform: uppercase;\r\n    text-align: center;\r\n    font-weight: bold;\r\n    font-style: normal;\r\n    font-size: 24px !important;\r\n    cursor: pointer;\r\n    border: 0px;\r\n    border-radius: 4px;\r\n    vertical-align: top;\r\n    height: auto;\r\n    line-height: 150%;\r\n}\r\n.wpst-acmp_sib_form_right {\r\n    width: 100% !important;\r\n  height: 844.4px !important;\r\n    border-radius: 7px 7px 0 0;\r\n    background-color: #000000;\r\n    color: #ffffff !important;\r\n    padding: 10px;\r\n}\r\n.wpst-acmp_sib_form_left, .wpst-iframe_desktop {\r\n    display: none !important;\r\n}\r\ninput[type=\"text\"] {\r\n    border: 1px solid #CCCCCC;\r\n    width: 100%;\r\n    background: #ffffff;\r\n    min-width: auto;\r\n    box-sizing: border-box;\r\n    padding: 8px 4px !important;\r\n    box-sizing: border-box;\r\n    -webkit-border-radius: 4px;\r\n    font-size: 13px;\r\n}\r\n  \r\n  \r\n  input[type=\"radio\"] {\r\n    font-size: 9px !important;\r\n}\r\n#gcaptcha {\r\n    transform: scale(0.857143);\r\n}\r\n.wpst-row2 {\r\n    padding: 5x 40px !important;\r\n}\r\n.g-recaptcha-response {\r\n    width: 250px;\r\n    height: 40px;\r\n    border: 1px solid rgb(193, 193, 193);\r\n    margin: 10px 25px;\r\n    padding: 0px;\r\n    resize: none;\r\n    display: none;\r\n}\r\n.wpst-alert-success {\r\n    margin-top: 0px !important;\r\n   \r\n}\r\n\r\n}\r\n\r\n\r\n<\/style>\r\n\r\n\r\n<div id=\"wps-container\">\r\n  <form name=\"ProfileForm\" onsubmit=\"return CheckInputs();\" action=\"https:\/\/link.ericfavre.com\/u\/register.php\" method=\"get\">\r\n      <input type=\"hidden\" name=\"CID\" value=\"793999487\">\r\n      <input type=\"hidden\" name=\"SID\" value=\"\">\r\n      <input type=\"hidden\" name=\"UID\" value=\"\">\r\n      <input type=hidden name=\"f\" value=\"1050\">\r\n      <input type=hidden name=\"p\" value=\"2\">\r\n      <input type=hidden name=\"a\" value=\"r\">\r\n      <input type=hidden name=\"el\" value=\"\">\r\n      <input type=hidden name=\"llid\" value=\"\">\r\n      <input type=hidden name=\"c\" value=\"\">\r\n      <input type=hidden name=\"counted\" value=\"\">\r\n      <input type=hidden name=\"RID\" value=\"\">\r\n      <input type=hidden name=\"mailnow\" value=\"\">\r\n      <!-- lead source -->\r\n      <input type=\"hidden\"  name=\"inp_11163\" value=\"form_blog_detox\"> \r\n      <!-- optin  -->\r\n      <input type=\"hidden\" name=\"optin\" value=\"y\">\r\n\r\n\r\n\r\n    <div class=\"wpst-elementor-widget-container\" id=\"EFform\">\r\n      <div class=\"wpst-acmp_sib_form\" style=\"text-align: center;display:flex;\" id=\"\">\r\n        <div style=\"width:50%;\" class=\"wpst-acmp_sib_form_left\"> <img src=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2021\/04\/DETOX2.jpg\" alt=\"\"> <\/div>\r\n        <div style=\"width:50%;\" class=\"wpst-acmp_sib_form_right\">\r\n          <picture>\r\n            <source srcset=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/11\/LOGO-ERIC-FAVRE-New-FdNoir-300x84.png\" media=\"(max-width: 767px)\">\r\n            <img src=\"https:\/\/www.ericfavre.com\/lifestyle\/wp-content\/uploads\/2020\/11\/LOGO-ERIC-FAVRE-New-FdBlanc-300x84.png\" alt=\"\"> <\/picture>\r\n          <p>&nbsp;<\/p>\r\n          <p><strong>RECOIS GRATUITEMENT LE GUIDE COMPLET DE LA DETOX<\/strong><\/p>\r\n          <p>&nbsp;<\/p>\r\n          <p>Retrouve dans ce Guide toutes les informations essentielles \u00e0 conna\u00eetre pour faire une d\u00e9tox efficace selon ton objectif.<\/p>\r\n          <div class=\"wpst-sib-container wpst-rounded ui-sortable\" style=\"border-radius: 4px; position: relative; margin: 0px; text-align: left; background: rgb(255, 255, 255); padding: 40px 20px 20px; border-width: 0px !important; border-color: transparent !important;\"> \r\n            \r\n            <!-- First Name -->\r\n            <div class=\"wpst-row \" style=\"font-size: 17px; position: relative; font-family: Helvetica Neue, Helvetica, Arial, sans-serif; color: rgb(0, 0, 0); left: 0px; top: 0px;\">\r\n              <div class=\"wpst-lbl-tinyltr\" contenteditable=\"false\" style=\"clear:both; float:none;\">Quel est ton Pr\u00e9nom ?<red style=\"color:#ff0000;\">*<\/red>\r\n              <\/div>\r\n              <input type=\"text\" name=\"inp_1\" id=\"PRENOM\" value=\"\" style=\"padding: 10px 2%; width: 100%; min-width: auto; box-sizing: border-box;\">\r\n              <div class=\"wpst-clear\" style=\"clear:both;\"><\/div>\r\n            <\/div>\r\n            \r\n            <!-- Gender -->\r\n            <div class=\"wpst-row\" style=\"font-size: 17px;\">\r\n              <div class=\"wpst-lbl-tinyltr\">Es-tu :<red style=\"color:#ff0000;\">*<\/red>\r\n              <\/div>\r\n              <div class=\"wpst-lbl-tinyltr\">\r\n                <input type=\"radio\" id=\"inp_5\" value=\"1\" name=\"inp_5\">\r\n                Un homme <\/div>\r\n              <div class=\"wpst-lbl-tinyltr\">\r\n                <input type=\"radio\" id=\"inp_5\" value=\"2\" name=\"inp_5\">\r\n                Une femme <\/div>\r\n              <div class=\"clear\" style=\"clear:both;\"><\/div>\r\n            <\/div>\r\n            \r\n            <!-- Email -->\r\n            <div class=\"wpst-row\" style=\"font-size: 17px;\">\r\n              <div class=\"wpst-lbl-tinyltr\">Ton E-mail pour recevoir le Guide&nbsp;\r\n                <red style=\"color:#ff0000;\">*<\/red>\r\n              <\/div>\r\n              <input type=\"text\" name=\"inp_3\" id=\"inp_3\" value=\"\" style=\"padding: 10px 2%; width: 100%; box-sizing: border-box;\" pattern=\"[^ @]*@[^ @]*\" required>\r\n              <div class=\"wpst-clear\"><\/div>\r\n            <\/div>\r\n            \r\n            <!-- Opt-In -->\r\n            <div class=\"wpst-row\" style=\"font-size: 17px; font-family:'Helvetica Neue', Helvetica, Arial, sans-serif; color:#000000;\">\r\n              <div contenteditable=\"false\" class=\"wpst-lbl-tinyltr\" style=\"clear:both;float:none;\"><br>\r\n              <\/div>\r\n              <div class=\"wpst-lbl-tinyltr\">\r\n                <input type=\"radio\" name=\"inp_1323\" value=\"1\" >\r\n                J'accepte de recevoir le Guide Detox et les Newsletters. <\/div>\r\n              <div class=\"wpst-clear\"><\/div>\r\n            <\/div>\r\n          <\/div>\r\n          <!-- reCaptcha -->\r\n          <div class=\"wpst-row wpst-row2\" style=\"font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; color: rgb(0, 0, 0); font-size: 17px;\">\r\n            <div id=\"gcaptcha\" >\r\n              <div style=\"width: 304px; height: 78px;\">\r\n                <div class=\"g-recaptcha\" data-sitekey=\"6LdkWcwqAAAAAHR0R1cynwDfW31BZoFwPdGChPOm\" data-callback=\"onReCaptchaSuccess\"><\/div>\r\n              <\/div>\r\n              <div class=\"wpst-clear\"><\/div>\r\n            <\/div>\r\n          <\/div>\r\n          <!-- Valider button -->\r\n          <div class=\"wpst-byline\" style=\"font-family: Helvetica Neue, Helvetica, Arial, sans-serif; color: rgb(52, 52, 52); font-weight: bold; font-size: 17px; text-align: center; display: block;\">\r\n            <button class=\"wpst-button wpst-editable \" type=\"submit\" data-editfield=\"subscribe\" contenteditable=\"false\" style=\"font-family: Helvetica Neue, Helvetica, Arial, sans-serif; color: rgb(255, 255, 255); background: rgb(0, 0, 0); display: inline-block; white-space: nowrap; min-height: 40px; margin: 0px 5px 0px 0px; padding: 0px 10px; text-decoration: none; text-transform: uppercase; text-align: center; font-weight: bold; font-style: normal; font-size: 28px; cursor: pointer; border: 0px; border-radius: 4px; vertical-align: top; height: auto; line-height: 120%;\">VALIDER<\/button>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/form>\r\n<\/div>\r\n\r\n<script>\r\ndocument.querySelector('button[type=\"submit\"]').addEventListener('click', function (event) {\r\n    event.preventDefault(); \/\/ Prevent immediate form submission\r\n\r\n    const efForm = document.getElementById('EFform');\r\n    const prenomInput = document.getElementById('PRENOM');\r\n    const emailInput = document.getElementById('inp_3');\r\n    const sexeInputs = document.getElementsByName('inp_5');\r\n    const optInInput = document.getElementsByName('inp_1323');\r\n    const recaptcha = document.querySelector('.g-recaptcha-response');\r\n    const errorMessages = document.querySelectorAll('.wpst-alert-danger');\r\n\r\n    \/\/ Clear any existing error or success messages\r\n    errorMessages.forEach(error => error.remove());\r\n    const successMessage = document.querySelector('.wpst-alert-success');\r\n    if (successMessage) successMessage.remove();\r\n\r\n    const rows = document.querySelectorAll('.wpst-row'); \r\n    rows.forEach(row => row.classList.remove('wpst-needsfilled')); \/\/ Clear all highlights\r\n\r\n    \/\/ Helper function to add an error message and highlight the row\r\n    \/\/ Updated function to add error messages with specific class\r\n    const addErrorMessage = (element, message, errorClass = 'wpst-alert-danger') => {\r\n      const parentRow = element.closest('.wpst-row');\r\n      parentRow.classList.add('wpst-needsfilled'); \/\/ Add the error class\r\n\r\n      const errorDiv = document.createElement('div');\r\n      errorDiv.className = `wpst-alert ${errorClass}`; \/\/ Dynamic error class\r\n      errorDiv.innerHTML = `${message}`; \/\/ Removed close button\r\n\r\n      parentRow.appendChild(errorDiv); \/\/ Append error message to the row\r\n    };\r\n\r\n    \/\/ Validation checks\r\n    let hasError = false;\r\n\r\n    \/\/ Validate Pr\u00e9nom\r\n    if (prenomInput.value.trim() === '') {\r\n        addErrorMessage(prenomInput, 'Ce champ est obligatoire.');\r\n        hasError = true;\r\n    }\r\n\r\n    \/\/ Validate \"Es-tu\" (Gender)\r\n    if (![...sexeInputs].some(input => input.checked)) {\r\n        const sexeParent = sexeInputs[0].closest('.wpst-row');\r\n        addErrorMessage(sexeParent, 'Ce champ est obligatoire.');\r\n        hasError = true;\r\n    }\r\n\r\n    \/\/ Validate Email\r\n    if (emailInput.value.trim() === '') {\r\n        addErrorMessage(emailInput, 'Ce champ est obligatoire.');\r\n        hasError = true;\r\n    } else if (!validateEmail(emailInput.value.trim())) {\r\n        addErrorMessage(emailInput, 'Veuillez entrer une adresse e-mail valide.');\r\n        hasError = true;\r\n    }\r\n\r\n    \/\/ Validate Opt-in\r\n    if (![...optInInput].some(input => input.checked)) {\r\n        const optInParent = optInInput[0].closest('.wpst-row');\r\n        addErrorMessage(optInParent, 'Ce champ est obligatoire.');\r\n        hasError = true;\r\n    }\r\n\r\n    \/\/ Validate reCAPTCHA\r\n    if (!recaptcha || recaptcha.value.trim() === '') {\r\n      const recaptchaParent = document.getElementById('gcaptcha').closest('.wpst-row');\r\n      addErrorMessage(recaptchaParent, 'Ce champ est obligatoire.', 'wpst-alert-recaptcha'); \/\/ Use specific class\r\n      hasError = true;\r\n    }\r\n\r\n    \/\/ If no errors, show loading GIF and then success message\r\n    if (!hasError) {\r\n        const form = document.querySelector('form[name=\"ProfileForm\"]');\r\n        form.submit(); \r\n        clearFields(); \/\/ Clear the fields\r\n    }\r\n});\r\n\r\n\/\/ Utility function to validate email format\r\nfunction validateEmail(inputText) {\r\n    var re = \/\\S+@\\S+\\.\\S+\/;\r\n    return re.test(inputText);\r\n}\r\n\r\n\/\/ Function to clear form fields\r\nfunction clearFields() {\r\n    document.getElementById('PRENOM').value = '';\r\n    document.getElementById('inp_3').value = '';\r\n    document.getElementsByName('inp_5').forEach(input => (input.checked = false));\r\n    document.getElementsByName('inp_1323').forEach(input => (input.checked = false));\r\n}\r\n\r\n\/\/ Add event listeners to clear error messages on focus or interaction\r\nconst inputs = document.querySelectorAll('#PRENOM, #inp_3, [name=\"inp_5\"], [name=\"inp_1323\"]');\r\ninputs.forEach(input => {\r\n    input.addEventListener('focus', () => {\r\n        const parentRow = input.closest('.wpst-row');\r\n        const error = parentRow.querySelector('.wpst-alert-danger');\r\n        if (error) error.remove();\r\n        parentRow.classList.remove('wpst-needsfilled');\r\n    });\r\n\r\n    if (input.type === 'radio') {\r\n        input.addEventListener('click', () => {\r\n            const parentRow = input.closest('.wpst-row');\r\n            const error = parentRow.querySelector('.wpst-alert-danger');\r\n            if (error) error.remove();\r\n            parentRow.classList.remove('wpst-needsfilled');\r\n        });\r\n    }\r\n});\r\n\r\n\/\/ ReCAPTCHA event to remove error message\r\nfunction onReCaptchaSuccess() {\r\n    const recaptchaParent = document.getElementById('gcaptcha').closest('.wpst-row');\r\n    const error = recaptchaParent.querySelector('.wpst-alert-recaptcha');\r\n    if (error) error.remove();\r\n    recaptchaParent.classList.remove('wpst-needsfilled');\r\n}\r\n\r\n\r\n\r\n<\/script>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84a88d2 elementor-widget elementor-widget-spacer\" data-id=\"84a88d2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c72245 elementor-widget elementor-widget-heading\" data-id=\"6c72245\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les burpees, \u00e7a sert \u00e0 quoi\u00a0?  <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4636cc03 elementor-widget elementor-widget-spacer\" data-id=\"4636cc03\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-478637f0 elementor-widget elementor-widget-text-editor\" data-id=\"478637f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>Les burpees sont souvent consid\u00e9r\u00e9s comme un <em>\u00ab calories killer \u00bb <\/em>ou tueur de calories, car il demande un\u00a0\u00a0effort cons\u00e9quent pour le corps.<\/p><p>\u00a0<\/p><p>Pour les sportifs dignes de ce nom, les int\u00e9r\u00eats \u00e0 r\u00e9aliser ce mouvement dans les entra\u00eenements sont nombreux.<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour am\u00e9liorer la condition physique {1) : r\u00e9alis\u00e9 sur des longues s\u00e9ries, les burpees sollicitent fortement le syst\u00e8me a\u00e9robie\u00a0;<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour am\u00e9liorer la r\u00e9sistance ana\u00e9robie, comme le montre l&#8217;\u00e9tude de Saka maki (2)\u00a0;<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour augmenter la sollicitation cardiaque et \u00e9nerg\u00e9tique d&#8217;un enchainement : en les ajoutant \u00e0 un ensemble d&#8217;exercices pour les rendre plus \u00abcardio\u00bb\u00a0;<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour am\u00e9liorer l&#8217;aisance \u00e0 son poids de corps : faire un burpee requiert de la mobilit\u00e9, de la coordination, et de la conscience corporelle\u00a0;<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour se d\u00e9passer, se challenger\u00a0: par exemple, se lancer le d\u00e9fi de faire 50 burpees (ou plus) et cela le plus vite possible\u00a0;<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour faire travailler facilement un groupe de sportif<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pour \u00ab sanctionner, punir\u00bb un sportif qui ne respecte pas les r\u00e8gles.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee4fb5d elementor-widget elementor-widget-spacer\" data-id=\"ee4fb5d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19f165a elementor-widget elementor-widget-spacer\" data-id=\"19f165a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74630ad3 elementor-widget elementor-widget-heading\" data-id=\"74630ad3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le test de Burpee  <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18707266 elementor-widget elementor-widget-spacer\" data-id=\"18707266\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22c4d4eb elementor-widget elementor-widget-text-editor\" data-id=\"22c4d4eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>Pour mesurer la condition physique, il existe le Test de Burpee. Celui-ci permet d\u2019\u00e9valuer la performance physique en fonction du nombre maximale de burpees r\u00e9alis\u00e9s, sans limite de temps et sans pause.<\/p><p>\u00a0<\/p><table width=\"644\"><tbody><tr><td width=\"322\"><p><strong>Nombre maximal de burpees<\/strong><\/p><\/td><td width=\"322\"><p><strong>Niveau de condition physique<\/strong><\/p><\/td><\/tr><tr><td width=\"322\"><p><strong>0 \u00e0 30<\/strong><\/p><\/td><td width=\"322\"><p><strong>Mauvais<\/strong><\/p><\/td><\/tr><tr><td width=\"322\"><p><strong>31 \u00e0 40<\/strong><\/p><\/td><td width=\"322\"><p><strong>Normal<\/strong><\/p><\/td><\/tr><tr><td width=\"322\"><p><strong>41 \u00e0 50<\/strong><\/p><\/td><td width=\"322\"><p><strong>Bon<\/strong><\/p><\/td><\/tr><tr><td width=\"322\"><p><strong>Plus de 60<\/strong><\/p><\/td><td width=\"322\"><p><strong>Excellent<\/strong><\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eabaf05 elementor-widget elementor-widget-spacer\" data-id=\"6eabaf05\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e884ce7 elementor-widget elementor-widget-heading\" data-id=\"4e884ce7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les variantes  <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6373d8d8 elementor-widget elementor-widget-spacer\" data-id=\"6373d8d8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cb7737a elementor-widget elementor-widget-text-editor\" data-id=\"3cb7737a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>Pour varier les plaisirs et se challenger, il existe plusieurs fa\u00e7ons de pimenter les burpees :<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees avec un gilet lest\u00e9<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees avec un saut par-dessus une barre de musculation<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees avec un saut par-dessus une box<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees avec mont\u00e9e de genoux lors du saut<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees avec une traction lors du saut<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00bd burpees : ne pas faire de pompes, ne pas faire de saut. Avec un d\u00e9part debout, il s\u2019agit de poser les mains au sol, de jeter les 2 jambes en arri\u00e8re, de ramener \u00e0 la poitrine et de se redresser<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees pistol : au lieu de sauter avec les 2 jambes, une fois en position group\u00e9e (genoux vers la poitrine), prendre appui sur 1 pied (pistol squat) et se redresser \u00e0 la force d\u2019une jambe<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Burpees avec salto arri\u00e8re\/avant : au lieu de sauter vers le haut en se relevant, il s\u2019agit de r\u00e9aliser un salto avant ou arri\u00e8re.<\/p><p>\u00a0<\/p><p>En bref, les burpees sont un excellent outil pour br\u00fbler des calories et am\u00e9liorer la condition physique ! Un must \u00e0 ins\u00e9rer dans les entrainements\u00a0!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-137e4308 elementor-widget elementor-widget-spacer\" data-id=\"137e4308\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff70221 elementor-widget elementor-widget-heading\" data-id=\"2ff70221\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9f\u00e9rences<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2801e736 elementor-widget elementor-widget-spacer\" data-id=\"2801e736\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-588551c1 elementor-widget elementor-widget-text-editor\" data-id=\"588551c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>(\/) : McRae, G., Payne, A., Zelt, J. G. E., Scribbans, T. D.,Jung, M. E., Little, J. P &amp; Gurd, B. J. (2012), Extremely low volume, whole-body aerobic-resistance training improves aerobic fitness and muscular endurance in females. App\/ied Physiology, Nutrition &amp; Metabolism, 37(6), 1124-1131 &#8230;.<\/p><p>\u00a0<\/p><p>(2)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0: Sakamaki, T. (1983). A study of the burpee push up test as simple method of measuring endurance. Nippon lka Daigaku Zasshi\/Journal Of The NipponMedical School, 50(2), 173-190&#8230;.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3317f7d6 elementor-widget elementor-widget-spacer\" data-id=\"3317f7d6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-762693bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"762693bd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2473a332\" data-id=\"2473a332\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-inner-section elementor-element elementor-element-5469e2d6 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5469e2d6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6d3c9d12\" data-id=\"6d3c9d12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ffc6c5b elementor-widget elementor-widget-heading\" data-id=\"4ffc6c5b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EN SAVOIR PLUS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-inner-section elementor-element elementor-element-515e29b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"515e29b0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5fcb4f78\" data-id=\"5fcb4f78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73717fa3 elementor-absolute elementor-widget elementor-widget-text-editor\" data-id=\"73717fa3\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>Nos autres <span style=\"color: #bd2929\">ressources<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37ed04e5 elementor-widget elementor-widget-spacer\" data-id=\"37ed04e5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-inner-section elementor-element elementor-element-7634fced elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7634fced\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct  elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-731deb66\" data-id=\"731deb66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51947407 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"51947407\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.ericfavre.com\/lifestyle\/pliometrie-les-exercices\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">PLIOMETRIE : LES EXERCICES A PRIVILEGIER<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Quand on commence \u00e0 faire du sport ou \u00e0 entreprendre des activit\u00e9s physiques, on n\u2019est&hellip;<\/p>\n","protected":false},"author":23,"featured_media":50961,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":[],"_links":{"self":[{"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/pages\/48161"}],"collection":[{"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/comments?post=48161"}],"version-history":[{"count":7,"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/pages\/48161\/revisions"}],"predecessor-version":[{"id":96938,"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/pages\/48161\/revisions\/96938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/media\/50961"}],"wp:attachment":[{"href":"https:\/\/www.ericfavre.com\/lifestyle\/wp-json\/wp\/v2\/media?parent=48161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}